{"id":33616,"date":"2024-08-05T15:23:11","date_gmt":"2024-08-05T15:23:11","guid":{"rendered":"https:\/\/test.suports.es\/?page_id=33616"},"modified":"2026-03-02T08:20:12","modified_gmt":"2026-03-02T08:20:12","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/www.suports.es\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"33616\" class=\"elementor elementor-33616 elementor-16120\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bdcb6f9 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"bdcb6f9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b36c1e\" data-id=\"0b36c1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e965e8 elementor-widget elementor-widget-heading\" data-id=\"4e965e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de Privacidad<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed6739e animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed6739e\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d379a4f\" data-id=\"d379a4f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecb6e0e elementor-widget elementor-widget-heading\" data-id=\"ecb6e0e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Introducci\u00f3n y definiciones<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5885a9 elementor-widget elementor-widget-text-editor\" data-id=\"c5885a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La presente pol\u00edtica tiene como objetivo informar a el interesado, en adelante el USUARIO, de los distintos tratamientos de datos personales asociados a los servicios ofrecidos en Internet por <a href=\"\/\">Gonvarri Solar Steel<\/a>.<\/p><p>Con la aceptaci\u00f3n de esta pol\u00edtica, usted acepta expresamente lo dispuesto en Pol\u00edtica de Privacidad y en el Aviso Legal y Condiciones de uso como USUARIO de los servicios ofrecidos por la \u00a0web de Gonvarri Solar Steel, cuya finalidad es ofrecer informaci\u00f3n de sus productos y soluciones y poner a disposici\u00f3n de los interesados un medio de contacto.<\/p><p>Para el correcto entendimiento de esta pol\u00edtica, se realizan las siguientes definiciones:<\/p><ul><li><strong>Usuario:<\/strong> ser\u00e1 aquella persona f\u00edsica o jur\u00eddica que acceda y\/o use la web y\/o los servicios ofrecidos por Gonvarri Solar Steel por cualquier medio sin necesidad de registrarse. Mediante la aceptaci\u00f3n de esta cl\u00e1usula, el Usuario acepta la Pol\u00edtica de Privacidad y las Condiciones de Gonvarri Solar Steel, reflejadas en el presente documento.<\/li><li><strong>Dato personal:<\/strong> un dato personal es cualquier informaci\u00f3n sobre una persona f\u00edsica identificada o identificable (el interesado). Se considera persona f\u00edsica identificable cualquier persona cuya identidad se puede determinar, directa o indirectamente, en particular mediante un identificador.<\/li><li><strong>Tratamiento de datos personales:<\/strong> cualquier operaci\u00f3n o conjunto de operaciones realizadas sobre datos personales o conjuntos de datos personales, ya sea por procedimientos automatizados o no, como la recogida, registro, organizaci\u00f3n, estructuraci\u00f3n, conservaci\u00f3n, adaptaci\u00f3n o modificaci\u00f3n, extracci\u00f3n, consulta, utilizaci\u00f3n, comunicaci\u00f3n por transmisi\u00f3n, difusi\u00f3n o cualquier otra forma de habilitaci\u00f3n de acceso, cotejo o interconexi\u00f3n, limitaci\u00f3n, supresi\u00f3n o destrucci\u00f3n.<\/li><li><strong>Servicios:<\/strong> abarcan todos los productos y acciones promocionales, ya sean gratuitos o de pago, que consisten en el acceso a diferentes informaciones, contenidos, comunicaciones comerciales y corporativas, programas, aplicaciones, tiendas, sitios web, v\u00eddeo bajo demanda o similares ofrecidos por Gonvarri Solar Steel.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec26559 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec26559\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06c2ecd\" data-id=\"06c2ecd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f47e4e elementor-widget elementor-widget-heading\" data-id=\"9f47e4e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Cumplimiento de la normativa vigente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5da73f8 elementor-widget elementor-widget-text-editor\" data-id=\"5da73f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gonvarri Solar Steel, al estar ubicado en Espa\u00f1a, est\u00e1 sometido al cumplimiento de la normativa espa\u00f1ola y europea en materia de protecci\u00f3n de datos y servicios de la sociedad de la informaci\u00f3n.<\/p><p>Los datos de car\u00e1cter personal del USUARIO se tratar\u00e1n de conformidad con lo dispuesto en la Pol\u00edtica de Privacidad de Datos Corporativa de Gonvarri Industries, basada en el Reglamento (UE) 2016\/679, de 27 de abril (GDPR), y la Ley Org\u00e1nica 3\/2018, de 5 de diciembre (LOPDGDD).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f2ce43c animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2ce43c\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22039cf\" data-id=\"22039cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f7305b elementor-widget elementor-widget-heading\" data-id=\"0f7305b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. Responsable del tratamiento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ae6b82 elementor-widget elementor-widget-text-editor\" data-id=\"3ae6b82\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los datos personales ser\u00e1n tratados por Gonvarri Corporaci\u00f3n Financiera, con direcci\u00f3n Prolongaci\u00f3n de, C. de Embajadores, S\/N, 28053 Madrid, tel\u00e9fono de contacto 913 79 19 00 y email <a href=\"mailto:Privacy.Enquiries@gonvarri.com\">Privacy.Enquiries@gonvarri.com<\/a> como responsable del tratamiento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae535c2 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae535c2\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c95b04d\" data-id=\"c95b04d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7463c42 elementor-widget elementor-widget-heading\" data-id=\"7463c42\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4. Finalidad de los tratamientos de los datos personales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04b5057 elementor-widget elementor-widget-text-editor\" data-id=\"04b5057\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64a2479 list-especial wcf-t-animation-none elementor-widget elementor-widget-wcf--text\" data-id=\"64a2479\" data-element_type=\"widget\" data-settings=\"{&quot;wcf-animation&quot;:&quot;fade&quot;,&quot;wcf_text_animation&quot;:&quot;none&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;fade-from&quot;:&quot;top&quot;,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50}\" data-widget_type=\"wcf--text.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"wcf--text\">Los siguientes tratamientos de los que es informado el USUARIO, ser\u00e1n ejecutados con la informaci\u00f3n de car\u00e1cter personal que ser\u00e1 facilitada por el mismo:\n<table>\n<thead>\n<tr>\n<th>Tratamiento<\/th>\n<th>Finalidad<\/th>\n<th>Datos personales recogidos<\/th>\n<th>Plazo de conservaci\u00f3n<\/th>\n<th>Cesi\u00f3n a Terceros<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Formulario Inscripci\u00f3n de oferta<\/td>\n<td>El env\u00edo de informaci\u00f3n curricular por parte del USUARIO con el fin de inscribirse en una oferta de empleo publicada en la web y entrar en el proceso de gesti\u00f3n de candidatos de Gonvarri Solar Steel.<\/td>\n<td>Expectativa salarial\nDisponibilidad para viajar\nFecha de Incorporaci\u00f3n\nCurriculum Vitae (Archivo adjunto)<\/td>\n<td>1 mes, siendo eliminados los datos personales tras ese periodo<\/td>\n<td>No se compartir\u00e1n con terceros<\/td>\n<\/tr>\n<tr>\n<td>Formulario Env\u00edanos tu CV<\/td>\n<td>El env\u00edo de informaci\u00f3n curricular por parte del USUARIO y entrar en el proceso de gesti\u00f3n de candidatos de Gonvarri Solar Steel.<\/td>\n<td>Curriculum Vitae (Archivo adjunto)<\/td>\n<td>1 mes, siendo eliminados los datos personales tras ese periodo<\/td>\n<td>No se compartir\u00e1n con terceros<\/td>\n<\/tr>\n<tr>\n<td>Formulario Contacta con Nosotros<\/td>\n<td>La solicitud de presupuesto mediante el env\u00edo de datos de contacto y del proyecto por parte del USUARIO con el fin de ser contactado por un comercial de Gonvarri Solar Steel.<\/td>\n<td>Nombre\nEmail\nTel\u00e9fono\nDepartamento\nEmpresa\nMensaje\nArchivos Adjuntos<\/td>\n<td>1 a\u00f1o, siendo eliminados los datos personales tras ese periodo<\/td>\n<td>No se compartir\u00e1n con terceros<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c343ec elementor-widget elementor-widget-text-editor\" data-id=\"5c343ec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64a2479 list-especial wcf-t-animation-none elementor-widget elementor-widget-wcf--text\" data-id=\"64a2479\" data-element_type=\"widget\" data-settings=\"{&quot;wcf-animation&quot;:&quot;fade&quot;,&quot;wcf_text_animation&quot;:&quot;none&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;fade-from&quot;:&quot;top&quot;,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50}\" data-widget_type=\"wcf--text.default\"><div class=\"elementor-widget-container\"><div class=\"wcf--text\"><div class=\"elementor-element elementor-element-46412da list-especial wcf-t-animation-none elementor-widget elementor-widget-wcf--text\" data-id=\"46412da\" data-element_type=\"widget\" data-settings=\"{&quot;wcf-animation&quot;:&quot;fade&quot;,&quot;wcf_text_animation&quot;:&quot;none&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;fade-from&quot;:&quot;top&quot;,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50}\" data-widget_type=\"wcf--text.default\"><div class=\"elementor-widget-container\"><div class=\"wcf--text\"><p>El tratamiento de datos personales espec\u00edficos asociados a las cookies se encuentra descrito en el Pol\u00edtica de Cookies de Gonvarri Solar Steel.<\/p><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a48e08 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a48e08\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0621f0\" data-id=\"c0621f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5497a3 elementor-widget elementor-widget-heading\" data-id=\"e5497a3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5. Legitimizaci\u00f3n para el tratamiento de los datos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa68f31 elementor-widget elementor-widget-text-editor\" data-id=\"aa68f31\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64a2479 list-especial wcf-t-animation-none elementor-widget elementor-widget-wcf--text\" data-id=\"64a2479\" data-element_type=\"widget\" data-settings=\"{&quot;wcf-animation&quot;:&quot;fade&quot;,&quot;wcf_text_animation&quot;:&quot;none&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;fade-from&quot;:&quot;top&quot;,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50}\" data-widget_type=\"wcf--text.default\"><div class=\"elementor-widget-container\"><div class=\"wcf--text\"><p>Para estos tratamientos la base y fundamento legal se encontrar\u00eda en:<\/p><ul><li>(GDPR art, 6.1.a) El USUARIO dio su consentimiento para el tratamiento de sus datos personales para uno o varios fines espec\u00edficos a trav\u00e9s de la web de Gonvarri Solar Steel.<\/li><li>(GDPR art. 6.1 f) el tratamiento es necesario para la satisfacci\u00f3n de intereses leg\u00edtimos perseguidos por el responsable del tratamiento, Gonvarri Solar Steel, que es la oferta de los servicios y de empleo ofrecidos en su web y el correcto funcionamiento de la misma.<\/li><\/ul><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a43ddd animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a43ddd\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5aa3d41\" data-id=\"5aa3d41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6290d0c elementor-widget elementor-widget-heading\" data-id=\"6290d0c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">6. Derechos de los usuarios en materia de protecci\u00f3n de datos personales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3533c61 elementor-widget elementor-widget-text-editor\" data-id=\"3533c61\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64a2479 list-especial wcf-t-animation-none elementor-widget elementor-widget-wcf--text\" data-id=\"64a2479\" data-element_type=\"widget\" data-settings=\"{&quot;wcf-animation&quot;:&quot;fade&quot;,&quot;wcf_text_animation&quot;:&quot;none&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;fade-from&quot;:&quot;top&quot;,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50}\" data-widget_type=\"wcf--text.default\"><div class=\"elementor-widget-container\"><div class=\"wcf--text\"><p>El USUARIO tiene derecho a acceder a sus datos personales, as\u00ed como a solicitar la rectificaci\u00f3n de los datos inexactos o, en su caso, solicitar su supresi\u00f3n cuando, entre otros motivos, los datos ya no sea necesarios para los fines que fueron recogidos.<\/p><p>En determinadas circunstancias, el USUARIO podr\u00e1 solicitar la limitaci\u00f3n del tratamiento de sus datos, en cuyo caso \u00fanicamente los conservaremos para el ejercicio o la defensa de reclamaciones.<\/p><p>En determinadas circunstancias y por motivos relacionados con su situaci\u00f3n particular, el USUARIO podr\u00e1 oponerse al tratamiento de sus datos. Gonvarri Solar Steel dejar\u00e1 de tratar los datos, salvo por motivos leg\u00edtimos imperiosos, o el ejercicio o la defensa de posibles reclamaciones.<\/p><p>Para ejercitar estos derechos, y para cualquier otra aclaraci\u00f3n, el USUARIO podr\u00e1 dirigirse por escrito a la direcci\u00f3n postal anteriormente indicada o a trav\u00e9s de la direcci\u00f3n de correo electr\u00f3nico siguiente <a href=\"mailto:Privacy.Rights@gonvarri.com\">Privacy.Rights@gonvarri.com<\/a> , siguiendo el procedimiento registrado en la web de Gonvarri Solar Steel.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4222d8d animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4222d8d\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6982ede\" data-id=\"6982ede\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-534cb0f elementor-widget elementor-widget-heading\" data-id=\"534cb0f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">7. M\u00e1s informaci\u00f3n sobre la Gesti\u00f3n de datos personales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b3e70c elementor-widget elementor-widget-text-editor\" data-id=\"5b3e70c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64a2479 list-especial wcf-t-animation-none elementor-widget elementor-widget-wcf--text\" data-id=\"64a2479\" data-element_type=\"widget\" data-settings=\"{&quot;wcf-animation&quot;:&quot;fade&quot;,&quot;wcf_text_animation&quot;:&quot;none&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;fade-from&quot;:&quot;top&quot;,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50}\" data-widget_type=\"wcf--text.default\"><div class=\"elementor-widget-container\"><div class=\"wcf--text\"><p>El USUARIO puede obtener m\u00e1s informaci\u00f3n sobre como Gonvarri Solar Steel y el grupo Gonvarri Industries trata los datos personales en el apartado web de <a href=\"https:\/\/www.gonvarri.com\/gestion-de-la-privacidad\/%20.\" target=\"_blank\" rel=\"noopener\">Gesti\u00f3n de la Privacidad.<\/a><\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Privacidad 1. Introducci\u00f3n y definiciones La presente pol\u00edtica tiene como objetivo informar a el interesado, en adelante el USUARIO, de los distintos tratamientos de datos personales asociados a los servicios ofrecidos en Internet por Gonvarri Solar Steel. Con la aceptaci\u00f3n de esta pol\u00edtica, usted acepta expresamente lo dispuesto en Pol\u00edtica de Privacidad y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-33616","page","type-page","status-publish","hentry"],"acf":[],"rankMath":{"parentDomain":"www.suports.es","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"La imagen destacada debe tener al menos 200 por 200 p\u00edxeles para que Facebook y otros sitios de redes sociales puedan escogerla.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"politica-de-privacidad","permalinkFormat":"https:\/\/www.suports.es\/es\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/www.suports.es\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"Esta pol\u00edtica ser\u00e1 de aplicaci\u00f3n en las p\u00e1gina de Solar Steel.","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"noindex":true},"twitterAuthor":"nombre de usuario","primaryTerm":0,"authorName":"desarrollo","titleTemplate":"%title% %page% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":true},"homeUrl":"https:\/\/www.suports.es\/es\/","objectID":33616,"objectType":"post","locale":"es","localeFull":"es_ES","overlayImages":{"play":{"name":"Icono de reproducci\u00f3n","url":"https:\/\/www.suports.es\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/vhost\/suports\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icono GIF","url":"https:\/\/www.suports.es\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/vhost\/suports\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/www.suports.es\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fwww.suports.es%2Fes%2F&r=https%3A%2F%2Fwww.suports.es%2Fes%2Fwp-json%2Fwp%2Fv2%2Fpages%2F33616%3Fnonce%3D0f5b56a9e9","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/www.suports.es\/wp-content\/uploads\/2024\/08\/gsolar-favicon.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Actualizar","trendsPreviewImage":"https:\/\/www.suports.es\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":false,"description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/www.suports.es\/es\/wp-json\/wp\/v2\/pages\/33616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.suports.es\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.suports.es\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.suports.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suports.es\/es\/wp-json\/wp\/v2\/comments?post=33616"}],"version-history":[{"count":14,"href":"https:\/\/www.suports.es\/es\/wp-json\/wp\/v2\/pages\/33616\/revisions"}],"predecessor-version":[{"id":36462,"href":"https:\/\/www.suports.es\/es\/wp-json\/wp\/v2\/pages\/33616\/revisions\/36462"}],"wp:attachment":[{"href":"https:\/\/www.suports.es\/es\/wp-json\/wp\/v2\/media?parent=33616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}